{"id":198595,"date":"2023-07-07T13:55:28","date_gmt":"2023-07-07T16:55:28","guid":{"rendered":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/?p=198595"},"modified":"2023-07-07T13:58:40","modified_gmt":"2023-07-07T16:58:40","slug":"chaco-festejos-por-el-dia-de-la-independencia-con-fiestas-populares-en-makalle-y-colonia-popular","status":"publish","type":"post","link":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/2023\/07\/07\/chaco-festejos-por-el-dia-de-la-independencia-con-fiestas-populares-en-makalle-y-colonia-popular\/","title":{"rendered":"CHACO:  Festejos Por El D\u00eda De La Independencia Con Fiestas Populares En Makall\u00e9 Y Colonia Popular"},"content":{"rendered":"\n<p>Autoridades del Instituto de Turismo del Chaco presentaron hoy la 30\u00aa edici\u00f3n de la Fiesta Provincial del Ternero que se realizar\u00e1 el pr\u00f3ximo domingo 9 de julio, en Makall\u00e9. Se trata de una celebraci\u00f3n que valora la cultura y el trabajo local de los gauchos con una gran jornada que comienza a las 9 y finaliza a las 2 de la madrugada del d\u00eda siguiente. Durante la conferencia de prensa, las autoridades lanzaron tambi\u00e9n una nueva edici\u00f3n del Festival del Gaucho en Colonia Popular.<\/p>\n\n\n\n<p>Se espera que unas 10.000 personas asistan a Makall\u00e9 el pr\u00f3ximo domingo. \u201cEs un hito tur\u00edstico, cultural e identitario con m\u00e1s de 11 agrupaciones musicales y m\u00e1s de 50 emprendedores que van a brindar una amplia oferta con el objetivo de posicionar el Turismo Receptivo Rural y de Naturaleza en la provincia\u201d, se\u00f1al\u00f3 el vicepresidente del Instituto de Turismo Mauro Flores.<\/p>\n\n\n\n<p>A su turno, el intendente Marcelo Angione destac\u00f3 el \u00e9xito de la edici\u00f3n anterior y coment\u00f3 que fue declarada de inter\u00e9s provincial y que la entrada es libre y gratuita. \u201cEste tipo de eventos tradicional nos representa y nos permite hacer conocida la localidad; hay muchas personas trabajando en la organizaci\u00f3n del mismo que ya cuenta con m\u00e1s de 30 a\u00f1os de trayectoria, lo que hace perdurar nuestro acervo cultural y mantiene nuestras tradiciones\u201d, y finaliz\u00f3 agradeciendo el apoyo del ITCh.<\/p>\n\n\n\n<p>Programa de la Fiesta Provincial Del Ternero<\/p>\n\n\n\n<p>Durante toda la jornada estar\u00e1n presentes emprendedores y artesanos locales. Comenzar\u00e1 a las 9, con desfile gaucho; 9.30 entrega de premios; a las 10, ser\u00e1 el inicio de las actividades vacunas; a las 13 est\u00e1 previsto el almuerzo criollo junto a grupo musical; a las 14, ser\u00e1 la segunda parte de actividades vacunas; a las 17 se realizar\u00e1n juegos de destreza gauchos; a 19.00 ser\u00e1 el momento de la elecci\u00f3n reina del Ternero; a las 19.30 se iniciar\u00e1 el baile popular y a las 2 de la madrugada culminar\u00e1 la jornada.<\/p>\n\n\n\n<p>Festival del Gaucho en Colonia Popular<\/p>\n\n\n\n<p>Adem\u00e1s, el ITCh promovi\u00f3 la sexta edici\u00f3n del Festival del Gaucho con fecha 9 de julio, cuya presentaci\u00f3n se realiz\u00f3 en compa\u00f1\u00eda del director de Promoci\u00f3n del Instituto de Turismo del Chaco, Jorge S\u00e1nchez; junto al intendente de Colonia Popular Juan Carlos Plozzer y el coordinador de la fiesta Beto G\u00f3mez. El jefe comunal se refiri\u00f3 a que \u201cla localidad espera a los visitantes todo el a\u00f1o\u201d.<\/p>\n\n\n\n<p>El Festival del Gaucho comenz\u00f3 en 2018 con el objetivo de mantener la identidad del pueblo, es una fiesta familiar donde m\u00e1s all\u00e1 de la jineteada con jinetes de un nivel de jerarqu\u00eda, tambi\u00e9n participan ni\u00f1os y ni\u00f1as con monta de oveja, adolescentes con carreras de embolsados, cursos de bailes, gastronom\u00eda y m\u00fasica con artistas de primer nivel.<\/p>\n\n\n\n<p>La jornada iniciar\u00e1 a las 8, con el izamiento en el Pabell\u00f3n Nacional; a las 8.30 se realizar\u00e1 el acto central en el Sal\u00f3n de Usos M\u00faltiples Municipal; a las 9.15 ser\u00e1 la concentraci\u00f3n de agrupaciones gauchas en la cancha municipal; a las 9:30 se efectuar\u00e1 el paseo gaucho; a las 9.45, ya en el predio de la doma, se izar\u00e1 el pabell\u00f3n nacional y el provincia en el predio de doma; a las 10 ser\u00e1 la elecci\u00f3n de la mejor agrupaci\u00f3n, el mejor montado y la vestimenta gaucha, el mejor menchito, el mejor mencho, la mejor china, la mejor suela, eel mejor cuero crudo, plata, estandarte.<\/p>\n\n\n\n<p>A las 10.30 se realizar\u00e1 la jineteada en la categor\u00eda grupal; 12 h actuar\u00e1n los Cunum\u00ed; 12.30 ser\u00e1 el turno del almuerzo criollo; a las 13 ser\u00e1 el show en vivo de Emiliano Cardozo y los Cardocitos; a las 13.45 se realizar\u00e1n los juegos camperos; 14.45 el concurso de baile con premio; a las 15:15 ser\u00e1 el turno de la jineteada categor\u00eda bastos; a las 17.30, la monta especial &#8220;Joaqu\u00edn Griolio vs El Carau&#8221;, Tropilla La Amistad de Cristian Jacobo, &#8220;Emiliano Lali vs El Camba&#8221;, Tropilla La Criolla de Juan Fern\u00e1ndez. A las 18 ser\u00e1 la actuaci\u00f3n de Las Estrellas y luego ser\u00e1 el turno de Agrupaci\u00f3n Herrera. El gran cierre ser\u00e1 a las 20, con la presencia de L\u00e1zaro Caballero.<\/p>\n\n\n\n<p>Link: https:\/\/comunicacion.chaco.gov.ar\/turismo\/static\/n\/72586<\/p>\n","protected":false},"excerpt":{"rendered":"<p>07-Jul-23  En conferencia de prensa autoridades del Instituto de Turismo del Chaco presentaron la 30\u00b0 Fiesta Provincial del Ternero en Makall\u00e9 y el 6\u00b0 Festival del Gaucho en Colonia Popular que se llevar\u00e1n a cabo este domingo 9 de julio.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[98],"tags":[],"_links":{"self":[{"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/posts\/198595"}],"collection":[{"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/comments?post=198595"}],"version-history":[{"count":1,"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/posts\/198595\/revisions"}],"predecessor-version":[{"id":198598,"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/posts\/198595\/revisions\/198598"}],"wp:attachment":[{"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/media?parent=198595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/categories?post=198595"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/tags?post=198595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}