{"id":365799,"date":"2026-05-13T08:25:05","date_gmt":"2026-05-13T11:25:05","guid":{"rendered":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/?p=365799"},"modified":"2026-05-13T08:25:10","modified_gmt":"2026-05-13T11:25:10","slug":"resistencia-comenzo-la-campana-de-recoleccion-diferenciada-de-residuos","status":"publish","type":"post","link":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/2026\/05\/13\/resistencia-comenzo-la-campana-de-recoleccion-diferenciada-de-residuos\/","title":{"rendered":"RESISTENCIA:    Comenz\u00f3 La Campa\u00f1a De Recolecci\u00f3n Diferenciada De Residuos"},"content":{"rendered":"\n<p>Se pueden depositar residuos reciclables, limpios y secos, como ser pl\u00e1sticos, metales, papel, cart\u00f3n, vidrios y RAEE (el\u00e9ctricos y electr\u00f3nicos).<\/p>\n\n\n\n<p>Desde la Secretar\u00eda de Ambiente y Movilidad Urbana explicaron que esta metodolog\u00eda forma parte de la oferta de servicios descentralizados que brinda la gesti\u00f3n Nikisch y que se desarrollar\u00e1 los s\u00e1bados.<\/p>\n\n\n\n<p>A las campa\u00f1as de vacunaci\u00f3n y desparasitaci\u00f3n del \u00e1rea de Veterinaria, se sum\u00f3 Ambiente, poniendo \u00e9nfasis a la higiene urbana, con recolecci\u00f3n diferenciada de residuos.<\/p>\n\n\n\n<p>Esta iniciativa consiste en colocar contenedores de diferentes colores para depositar distintos tipos de desperdicios.<\/p>\n\n\n\n<p>Para que la comunidad sepa de la misma, personal de la Secretar\u00eda de Desarrollo Humano recorre los barrios poniendo en conocimiento de la actividad y se informen qu\u00e9 tipos de residuos pueden depositar, que deben inorg\u00e1nicos.<\/p>\n\n\n\n<p>\u201cHasta aqu\u00ed estuvimos trabajando en estabilizar todo el sistema de recolecci\u00f3n de residuos domiciliarios, y ahora sumamos esta modalidad que tiene dos formas diferentes. Una es que el vecino pueda llevarlos en los lugares itinerantes, como es este caso, o a la avenida Soberan\u00eda Nacional 3.050, que es el centro de acopio municipal, si tiene veh\u00edculo propio\u201d, agregaron.<\/p>\n\n\n\n<p>Otra manera es a trav\u00e9s del CAD, que es el Centro de Atenci\u00f3n Digital, donde se puede solicitar para que se lo retire del domicilio de los vecinos.<\/p>\n\n\n\n<p>Y a modo de reconocimiento por el aporte de la gente, se le ofrece en forma gratuita un plant\u00edn de alguna especie aut\u00f3ctona del Vivero Municipal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>13-May-26 La Municipalidad de Resistencia sum\u00f3 el Sistema de Recolecci\u00f3n Diferenciada de residuos a los servicios que brinda. Se trata de una iniciativa que consiste en la colocaci\u00f3n de contenedores especiales en espacios p\u00fablicos, en fechas y lugares rotativos.<\/p>\n","protected":false},"author":3,"featured_media":365800,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[102],"tags":[],"_links":{"self":[{"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/posts\/365799"}],"collection":[{"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/comments?post=365799"}],"version-history":[{"count":1,"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/posts\/365799\/revisions"}],"predecessor-version":[{"id":365801,"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/posts\/365799\/revisions\/365801"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/media\/365800"}],"wp:attachment":[{"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/media?parent=365799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/categories?post=365799"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/tags?post=365799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}