{"id":365832,"date":"2026-05-13T09:29:28","date_gmt":"2026-05-13T12:29:28","guid":{"rendered":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/?p=365832"},"modified":"2026-05-13T09:29:31","modified_gmt":"2026-05-13T12:29:31","slug":"curuzu-cuatia-narcomenudeo-secuestraron-cocaina-dinero-y-dos-motocicletas","status":"publish","type":"post","link":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/2026\/05\/13\/curuzu-cuatia-narcomenudeo-secuestraron-cocaina-dinero-y-dos-motocicletas\/","title":{"rendered":"CURUZ\u00da CUATI\u00c1: Narcomenudeo: Secuestraron Coca\u00edna, Dinero Y Dos Motocicletas"},"content":{"rendered":"\n<p>Un operativo contra el narcomenudeo en la localidad correntina de Curuz\u00fa Cuati\u00e1 permiti\u00f3 el secuestro de coca\u00edna, dinero en efectivo y dos motocicletas. El procedimiento fue concretado este lunes luego de una investigaci\u00f3n de varias semanas que termin\u00f3 con dos personas demoradas.<\/p>\n\n\n\n<p>El allanamiento se realiz\u00f3 en una vivienda ubicada sobre calle Saavedra al 600, en el barrio Centenario. Participaron polic\u00edas de varias comisar\u00edas de la ciudad, adem\u00e1s del Grupo T\u00e1ctico Operacional de la Unidad Regional III.<\/p>\n\n\n\n<p>De acuerdo con la informaci\u00f3n policial, el allanamiento fue resultado de una investigaci\u00f3n que ven\u00eda desarroll\u00e1ndose desde hace varias semanas. Durante el procedimiento, se encontraron varias dosis de coca\u00edna.<\/p>\n\n\n\n<p>Adem\u00e1s de la droga, la Polic\u00eda secuestr\u00f3 dos motocicletas, una Honda Tornado y una Guerrero Dax. Tambi\u00e9n incautaron dinero en efectivo considerado de inter\u00e9s para la causa.<\/p>\n\n\n\n<p>Supervisi\u00f3n policial<\/p>\n\n\n\n<p>En el lugar estuvo presente el jefe de la Polic\u00eda de Corrientes, Miguel \u00c1ngel Leguizam\u00f3n, quien supervis\u00f3 el desarrollo del procedimiento.<\/p>\n\n\n\n<p>Como resultado del operativo, los dos demorados fueron trasladados junto a los elementos secuestrados a la comisar\u00eda correspondiente, donde continuaron las actuaciones judiciales de rigor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>13-May-26 Adem\u00e1s, dos personas fueron demoradas durante el allanamiento. <\/p>\n","protected":false},"author":4,"featured_media":365833,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[139],"tags":[],"_links":{"self":[{"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/posts\/365832"}],"collection":[{"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/comments?post=365832"}],"version-history":[{"count":1,"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/posts\/365832\/revisions"}],"predecessor-version":[{"id":365834,"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/posts\/365832\/revisions\/365834"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/media\/365833"}],"wp:attachment":[{"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/media?parent=365832"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/categories?post=365832"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/tags?post=365832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}