{"id":365850,"date":"2026-05-13T11:05:24","date_gmt":"2026-05-13T14:05:24","guid":{"rendered":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/?p=365850"},"modified":"2026-05-13T11:05:28","modified_gmt":"2026-05-13T14:05:28","slug":"puerto-vilelas-avanzan-trabajos-de-saneamiento-y-relevamiento-en-el-jardin-n-54","status":"publish","type":"post","link":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/2026\/05\/13\/puerto-vilelas-avanzan-trabajos-de-saneamiento-y-relevamiento-en-el-jardin-n-54\/","title":{"rendered":"PUERTO VILELAS:   Avanzan Trabajos De Saneamiento Y Relevamiento En El Jard\u00edn N\u00b0 54"},"content":{"rendered":"\n<p>Del recorrido participaron la directora regional Miriam G\u00f3mez, la arquitecta Mabel Betik, la coordinadora de educaci\u00f3n y cultura Eliana Rey&nbsp; y Rub\u00e9n Torres,&nbsp; funcionario de obras y servicios p\u00fablicos,&nbsp; quienes trabajaron de manera articulada junto al municipio para coordinar acciones destinadas a la reparaci\u00f3n del muro del edificio escolar y el acondicionamiento general del espacio.<\/p>\n\n\n\n<p>Adem\u00e1s, durante la jornada se llev\u00f3 adelante un relevamiento integral de las necesidades de la instituci\u00f3n educativa, con el fin de gestionar soluciones y dar respuesta a los distintos requerimientos planteados por la comunidad escolar.<\/p>\n\n\n\n<p>Desde el municipio destacaron que se contin\u00faa acompa\u00f1ando de manera permanente a las instituciones educativas de la localidad, mediante el trabajo conjunto y la presencia territorial, priorizando mejoras en infraestructura y condiciones adecuadas para estudiantes y docentes.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>13-May-26   La Municipalidad de Puerto Vilelas, a trav\u00e9s de la Coordinaci\u00f3n de Cultura y Educaci\u00f3n, realiz\u00f3 este lunes una visita al Jard\u00edn N\u00b0 54 \u201cGaspar de Nicola\u201d con el objetivo de avanzar en tareas de saneamiento y mejoras edilicias en la instituci\u00f3n.<\/p>\n","protected":false},"author":3,"featured_media":365854,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[108,101],"tags":[],"_links":{"self":[{"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/posts\/365850"}],"collection":[{"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/comments?post=365850"}],"version-history":[{"count":1,"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/posts\/365850\/revisions"}],"predecessor-version":[{"id":365855,"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/posts\/365850\/revisions\/365855"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/media\/365854"}],"wp:attachment":[{"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/media?parent=365850"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/categories?post=365850"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/tags?post=365850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}