{"id":365875,"date":"2026-05-13T13:05:31","date_gmt":"2026-05-13T16:05:31","guid":{"rendered":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/?p=365875"},"modified":"2026-05-13T13:05:34","modified_gmt":"2026-05-13T16:05:34","slug":"resistencia-duartango-llega-a-la-usina-cultural-con-merienda-y-show","status":"publish","type":"post","link":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/2026\/05\/13\/resistencia-duartango-llega-a-la-usina-cultural-con-merienda-y-show\/","title":{"rendered":"RESISTENCIA: Duartango llega A La Usina Cultural Con Merienda y Show"},"content":{"rendered":"\n<p>Las tarjetas para la velada ya est\u00e1n en venta. Para solicitar reservas, los interesados deben contactarse al tel\u00e9fono 3624-011788.<\/p>\n\n\n\n<p>Adem\u00e1s de las presentaciones en vivo y la merienda, el p\u00fablico podr\u00e1 participar de sorteos y juegos especiales. \u201cSe trata de un evento pensado no s\u00f3lo como un espacio de encuentro, sino tambi\u00e9n como una propuesta art\u00edstica y cultural donde la danza, la m\u00fasica y la calidez de nuestra familia se har\u00e1n presentes\u201d, describi\u00f3 el presidente de la Asociaci\u00f3n Civil Duartango, Jorge G\u00f3mez.&nbsp;<\/p>\n\n\n\n<p>\u201cCreemos profundamente en el valor del trabajo colectivo y en la importancia de sostener espacios culturales que generan identidad, pertenencia y oportunidades. La actividad tiene como objetivo colaborar con el sostenimiento de nuestra instituci\u00f3n, que d\u00eda a d\u00eda trabaja en la formaci\u00f3n art\u00edstica y en la contenci\u00f3n de ni\u00f1os, j\u00f3venes y adultos a trav\u00e9s del arte\u201d, agreg\u00f3.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>13-May-26 Este s\u00e1bado 16 de mayo a las 17, en la Usina Cultural, se realizar\u00e1 la Merienda y Show de Duartango, donde los asistentes podr\u00e1n compartir un refrigerio mientras disfrutan espect\u00e1culos de folclore y tango a cargo de los bailarines de la Academia.  <\/p>\n","protected":false},"author":3,"featured_media":365876,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[105],"tags":[],"_links":{"self":[{"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/posts\/365875"}],"collection":[{"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/comments?post=365875"}],"version-history":[{"count":1,"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/posts\/365875\/revisions"}],"predecessor-version":[{"id":365877,"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/posts\/365875\/revisions\/365877"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/media\/365876"}],"wp:attachment":[{"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/media?parent=365875"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/categories?post=365875"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/tags?post=365875"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}