{"id":365937,"date":"2026-05-13T17:41:01","date_gmt":"2026-05-13T20:41:01","guid":{"rendered":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/?p=365937"},"modified":"2026-05-13T17:41:06","modified_gmt":"2026-05-13T20:41:06","slug":"resistencia-intento-ingresar-estupefacientes-durante-una-visita-en-comisaria-y-fue-demorada","status":"publish","type":"post","link":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/2026\/05\/13\/resistencia-intento-ingresar-estupefacientes-durante-una-visita-en-comisaria-y-fue-demorada\/","title":{"rendered":"RESISTENCIA:   Intent\u00f3 Ingresar Estupefacientes Durante Una Visita En Comisar\u00eda Y Fue Demorada"},"content":{"rendered":"\n<p>El procedimiento se registr\u00f3 cerca de las 14:30, cuando la mujer de 50 a\u00f1os se present\u00f3 en la dependencia policial y, al ser sometida a la requisa de rutina, los efectivos hallaron entre sus prendas varios envoltorios de polietileno que conten\u00edan marihuana.<br>Ante esta situaci\u00f3n, se dio inmediata intervenci\u00f3n a la Divisi\u00f3n Microtr\u00e1fico, cuyos efectivos realizaron las pruebas de campo correspondientes, confirmando que se trataba de cannabis con un peso total de siete gramos.<br>Conforme a lo dispuesto por la Fiscal\u00eda Antidrogas N\u00b0 1, la mujer fue notificada de su aprehensi\u00f3n en una causa por supuesta infracci\u00f3n a la Ley Nacional de Estupefacientes N\u00b0 23.737.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>13-May-26    Una mujer fue demorada en la Comisar\u00eda Primera Metropolitana, luego de que personal policial detectara sustancias estupefacientes entre sus pertenencias cuando intentaba ingresar para realizar una visita.<\/p>\n","protected":false},"author":3,"featured_media":365938,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[103],"tags":[],"_links":{"self":[{"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/posts\/365937"}],"collection":[{"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/comments?post=365937"}],"version-history":[{"count":1,"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/posts\/365937\/revisions"}],"predecessor-version":[{"id":365939,"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/posts\/365937\/revisions\/365939"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/media\/365938"}],"wp:attachment":[{"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/media?parent=365937"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/categories?post=365937"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/tags?post=365937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}