{"id":1634,"date":"2019-10-23T23:59:43","date_gmt":"2019-10-24T02:59:43","guid":{"rendered":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/?p=1634"},"modified":"2019-10-23T23:59:45","modified_gmt":"2019-10-24T02:59:45","slug":"saenz-pena-una-mujer-fallecio-luego-de-participar-en-un-accidente-de-transito","status":"publish","type":"post","link":"https:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/2019\/10\/23\/saenz-pena-una-mujer-fallecio-luego-de-participar-en-un-accidente-de-transito\/","title":{"rendered":"S\u00c1ENZ PE\u00d1A: Una Mujer Fallecio Luego De Participar En Un Accidente De Transito"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img src=\"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-content\/uploads\/2019\/10\/GOL-SP.jpg\" alt=\"\" class=\"wp-image-1622\"\/><\/figure>\n\n\n\n<p>Olga Amanda Cancinos de 62 a\u00f1os falleci\u00f3 esta tarde en un\nsanatorio c\u00e9ntrico de la ciudad termal, debido a la lesi\u00f3n que sufriera en un\naccidente de tr\u00e1nsito ocurrido en Ruta Nacional N\u00ba 16 y calle 28.<\/p>\n\n\n\n<p>Hoy a las 11.30 aproximadamente, los agentes de la\nSegunda de S\u00e1enz Pe\u00f1a, fueron informados de un siniestro vial en Ruta Nacional\nN\u00ba 16 y calle 28. Al llegar, tomaron conocimiento que una mujer de 62 a\u00f1os, que\nviajaba de acompa\u00f1ante en un autom\u00f3vil Volkswagen Gol, color gris hab\u00eda sido\ntrasladada a un centro m\u00e9dico, debido a que sufri\u00f3 un golpe en su cabeza,\nquedando en el lugar su hijo de 32 a\u00f1os, que conduc\u00eda el rodado y su hija de\n33, estos dos no presentaba lesiones.<\/p>\n\n\n\n<p>La otra parte, se trataba de un Chevrolet Classic, color\ngris, conducido por un hombre de 36 a\u00f1os en compa\u00f1\u00eda de su sobrino de 17,\nno&nbsp; sufriendo lesiones.<\/p>\n\n\n\n<p>Se dio intervenci\u00f3n a la Divisi\u00f3n Medicina Legal&nbsp; y se realiz\u00f3 acta de constataci\u00f3n en el lugar\nen presencia de Personal de la Divisi\u00f3n Criminal\u00edstica, contando con la\ncolaboraci\u00f3n en la regulaci\u00f3n de tr\u00e1nsito, con personal de Tr\u00e1nsito Municipal y\nDivisi\u00f3n Tr\u00e1nsito Urbano y Patrulla Vial de esa ciudad.<\/p>\n\n\n\n<p>Posteriormente, a las 20 aproximadamente, desde la\nDivisi\u00f3n Medicina Legal comunicaron que desde el centro m\u00e9dico privado,\ninformaron el fallecimiento de Cancinos, debido a las lesiones sufridas en el\naccidente.<\/p>\n\n\n\n<p>Del hecho mencionado se pudo comunicar de esta novedad al\nDr. Marcelo Fabian Soto de la Fiscal\u00eda N\u00b0 3, quien dispuso se caratule las\nActuaciones como \u201cSupuesto Homicidio Culposo en Accidente de Transito\u201d y el\ncuerpo sea entregado a sus familiares fines p\u00f3stumos.-<\/p>\n","protected":false},"excerpt":{"rendered":"<p>23-Oct-19    Ocurri\u00f3 esta ma\u00f1ana. Del siniestro participaron dos veh\u00edculos, en uno de ellos viajaba la occisa junto a sus hijos. Falleci\u00f3 en un sanatorio c\u00e9ntrico debido a la lesi\u00f3n que sufri\u00f3 en su cabeza.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[103],"tags":[],"_links":{"self":[{"href":"https:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/posts\/1634"}],"collection":[{"href":"https:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/comments?post=1634"}],"version-history":[{"count":1,"href":"https:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/posts\/1634\/revisions"}],"predecessor-version":[{"id":1635,"href":"https:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/posts\/1634\/revisions\/1635"}],"wp:attachment":[{"href":"https:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/media?parent=1634"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/categories?post=1634"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/tags?post=1634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}