{"id":368373,"date":"2026-05-28T14:16:48","date_gmt":"2026-05-28T17:16:48","guid":{"rendered":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/?p=368373"},"modified":"2026-05-28T14:16:51","modified_gmt":"2026-05-28T17:16:51","slug":"chaco-campo-bedogni-el-gobernador-zdero-inauguro-el-nuevo-edificio-escolar-para-los-tres-niveles","status":"publish","type":"post","link":"https:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/2026\/05\/28\/chaco-campo-bedogni-el-gobernador-zdero-inauguro-el-nuevo-edificio-escolar-para-los-tres-niveles\/","title":{"rendered":"CHACO: Campo Bedogni: El Gobernador Zdero Inaugur\u00f3 El Nuevo Edificio Escolar Para Los Tres Niveles"},"content":{"rendered":"\n<p>El gobernador Leandro Zdero inaugur\u00f3 este jueves en la Legua 37, Paraje Campo Bedogni, de Juan Jos\u00e9 Castelli, la obra del nuevo edificio donde funcionar\u00e1n la Escuela de Educaci\u00f3n Primaria N\u00b0 733 \u201cEj\u00e9rcito Argentino\u201d, la Escuela de Educaci\u00f3n Secundaria N\u00b0 166 \u201cHermanos Bedogni\u201d y el anexo de Nivel Inicial, garantizando as\u00ed los tres niveles obligatorios en el coraz\u00f3n de El Impenetrable chaque\u00f1o.<\/p>\n\n\n\n<p>Durante el acto, el mandatario provincial destac\u00f3 que \u201cla educaci\u00f3n tiene sentido si nuestros chicos aprenden, en el campo, en un paraje o en la ciudad, chaque\u00f1os todos con la misma posibilidad\u201d, remarcando que en la provincia \u201cse ven cambios trascendentales\u201d vinculados a un rumbo claro en materia educativa.<\/p>\n\n\n\n<p>En esa l\u00ednea, Zdero agradeci\u00f3 el compromiso de los docentes chaque\u00f1os y especialmente de las maestras jardineras, en el marco del D\u00eda de los Jardines de Infantes y de las Maestras Jardineras. \u201cEstamos llevando adelante una gran tarea para brindar una mejor calidad educativa, y eso ya comienza a notarse en la lectoescritura de los estudiantes del primer ciclo\u201d, afirm\u00f3.<\/p>\n\n\n\n<p>Asimismo, se\u00f1al\u00f3 que desde el Ministerio de Educaci\u00f3n no s\u00f3lo se trabaja en infraestructura escolar, sino tambi\u00e9n en la transformaci\u00f3n educativa integral. \u201cEl Programa M\u00e1s Escuela viene trabajando en toda la provincia para mantener los edificios escolares. Adem\u00e1s, la capacitaci\u00f3n acompa\u00f1a a los docentes tanto de los parajes m\u00e1s alejados como de las ciudades, para que exista un mismo hilo conductor en el aprendizaje\u201d, expres\u00f3.<\/p>\n\n\n\n<p>El gobernador tambi\u00e9n subray\u00f3 la importancia de fortalecer el m\u00e9rito y el esfuerzo en el nivel Secundario: \u201cNo solamente estamos ordenando el sistema educativo, sino consolidando la posibilidad de superaci\u00f3n de nuestros j\u00f3venes para que puedan forjar su futuro\u201d.<\/p>\n\n\n\n<p>La educaci\u00f3n como herramienta de igualdad<\/p>\n\n\n\n<p>Por su parte, la ministra de Educaci\u00f3n, Sof\u00eda Naidenoff, resalt\u00f3 la decisi\u00f3n pol\u00edtica del gobernador de priorizar las escuelas rurales. \u201cEl gobernador puso la mirada en el monte chaque\u00f1o, donde las escuelas tienen mucho menos alumnos que en otras zonas. La educaci\u00f3n es la \u00fanica oportunidad de superaci\u00f3n personal\u201d, sostuvo.<\/p>\n\n\n\n<p>Adem\u00e1s, remarc\u00f3 la importancia de garantizar oportunidades educativas en cada rinc\u00f3n del territorio provincial. \u201cCuando el gobernador pone el acento en hacer una escuela ac\u00e1, est\u00e1 marcando un norte: que la educaci\u00f3n debe darse en toda la provincia de la misma manera y forma\u201d, afirm\u00f3.<\/p>\n\n\n\n<p>La directora de la EEP N\u00b0 733, Laura Escalante, expres\u00f3 su emoci\u00f3n por la concreci\u00f3n de la obra: \u201cHoy es un d\u00eda de inmensa alegr\u00eda y responsabilidad. Esta instituci\u00f3n es mucho m\u00e1s que un edificio nuevo, es un lugar donde los ni\u00f1os podr\u00e1n iniciar la primaria y los j\u00f3venes continuar la secundaria, creciendo juntos en un espacio moderno, seguro y lleno de oportunidades\u201d.<\/p>\n\n\n\n<p>En tanto, el director de la EES N\u00b0 166, H\u00e9ctor Lozicki, destac\u00f3 que el establecimiento secundario es el \u00fanico de la zona rural y recibe estudiantes de distintas comunidades cercanas. Actualmente, entre Nivel Inicial, Primario y Secundario, la matr\u00edcula total alcanza los 80 alumnos.<\/p>\n\n\n\n<p>A su turno, la subsecretaria de Infraestructura Escolar, Rosana Cerrutti, detall\u00f3 que la obra incluy\u00f3 la construcci\u00f3n de nuevas aulas y la refacci\u00f3n integral del edificio existente destinado al jard\u00edn de infantes. \u201cEstamos trabajando muy bien con el Programa Mejor Escuela para llegar a m\u00e1s instituciones de toda la provincia\u201d, indic\u00f3, precisando que ya se intervinieron m\u00e1s de 600 establecimientos educativos.<\/p>\n\n\n\n<p>La obra contempl\u00f3 la ampliaci\u00f3n con la construcci\u00f3n del nuevo edificio para la EEP N\u00b0 733 y la EES N\u00b0 166, adem\u00e1s de la refacci\u00f3n del antiguo edificio para el funcionamiento del anexo de Nivel Inicial.<\/p>\n\n\n\n<p>La inversi\u00f3n total, financiada con fondos provinciales e incluy\u00f3 tambi\u00e9n el mobiliario escolar.<\/p>\n\n\n\n<p>Acompa\u00f1aron el acto, las subsecretarias de Educaci\u00f3n, Isabel Sanchuk, y de Infraestructura Escolar, Rosana Cerrutti; el intendente Oscar Sander; el director de la Regional Educativa 2, Humberto Molina, entre otras autoridades.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>28-May-26 La obra beneficia a estudiantes de Nivel Inicial, Primario y Secundario de la Legua 37 &#8211; Paraje Campo Bedogni, en jurisdicci\u00f3n de Juan Jos\u00e9 Castelli.<\/p>\n","protected":false},"author":4,"featured_media":368374,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[98],"tags":[],"_links":{"self":[{"href":"https:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/posts\/368373"}],"collection":[{"href":"https:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/comments?post=368373"}],"version-history":[{"count":1,"href":"https:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/posts\/368373\/revisions"}],"predecessor-version":[{"id":368376,"href":"https:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/posts\/368373\/revisions\/368376"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/media\/368374"}],"wp:attachment":[{"href":"https:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/media?parent=368373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/categories?post=368373"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/tags?post=368373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}