{"id":375750,"date":"2026-07-15T10:23:39","date_gmt":"2026-07-15T13:23:39","guid":{"rendered":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/?p=375750"},"modified":"2026-07-15T10:23:41","modified_gmt":"2026-07-15T13:23:41","slug":"chaco-el-newcom-60-sigue-creciendo-en-chaco-con-el-acompanamiento-del-instituto-del-deporte","status":"publish","type":"post","link":"https:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/2026\/07\/15\/chaco-el-newcom-60-sigue-creciendo-en-chaco-con-el-acompanamiento-del-instituto-del-deporte\/","title":{"rendered":"CHACO: El Newcom +60 Sigue Creciendo En Chaco Con El Acompa\u00f1amiento Del Instituto Del Deporte"},"content":{"rendered":"\n<p>Fue en el marco del hist\u00f3rico reconocimiento de esta disciplina como deporte oficial de la provincia, tras la aprobaci\u00f3n por unanimidad de la ley en la Legislatura chaque\u00f1a.<\/p>\n\n\n\n<p>La normativa marc\u00f3 un antes y un despu\u00e9s para esta actividad, al permitir que el Estado acompa\u00f1e de manera institucional su crecimiento. En los \u00faltimos a\u00f1os, el newcom sum\u00f3 cientos de practicantes en distintos puntos del Chaco, consolid\u00e1ndose como una propuesta deportiva y recreativa destinada principalmente a personas mayores.<\/p>\n\n\n\n<p>Durante la jornada de ayer, el presidente del Instituto del Deporte, Fabio V\u00e1zquez, destac\u00f3 la importancia de la convocatoria y el impacto social de la disciplina. \u201cEstamos felices de ver a tantos adultos que se dedican a este deporte y que participan de una nueva fecha de este torneo con equipos de distintos lugares de la provincia\u201d, expres\u00f3.<\/p>\n\n\n\n<p>El funcionario remarc\u00f3 que el newcom no solo promueve la actividad f\u00edsica y contribuye a mejorar la calidad de vida, sino que tambi\u00e9n fortalece los v\u00ednculos sociales y familiares. \u201cExiste una gran camarader\u00eda entre quienes practican este deporte. Se conocen personas de diferentes localidades, comparten experiencias y participan de otras actividades que desarrollamos diariamente desde el Instituto del Deporte. Eso es fundamental para nosotros\u201d, se\u00f1al\u00f3 V\u00e1zquez.<\/p>\n\n\n\n<p>El newcom es una modalidad adaptada del v\u00f3leibol, dise\u00f1ada especialmente para personas mayores. Combina el ejercicio f\u00edsico con la recreaci\u00f3n y el esp\u00edritu competitivo, y actualmente es practicado por hombres y mujeres de entre 40 y m\u00e1s de 70 a\u00f1os en clubes, municipios y centros comunitarios de toda la provincia.<\/p>\n\n\n\n<p>Por su parte, el \u00e1rbitro Juan Carlos Moyano destac\u00f3 el acompa\u00f1amiento del Gobierno provincial para el desarrollo del certamen. \u201cEs una liga totalmente gratuita que puede realizarse gracias al Gobierno del Chaco. Participan 30 equipos distribuidos en dos categor\u00edas. En esta fecha compitieron seis equipos en las dos canchas del polideportivo y todav\u00eda resta un importante recorrido para completar este campeonato tan significativo para los adultos mayores\u201d, afirm\u00f3.<\/p>\n\n\n\n<p>Con este acompa\u00f1amiento, el Gobierno del Chaco contin\u00faa fortaleciendo el deporte como una herramienta de inclusi\u00f3n, bienestar e integraci\u00f3n social, promoviendo espacios que favorecen una vida activa y saludable para los adultos mayores.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>15-Jul-26   El Instituto del Deporte del Chaco acompa\u00f1\u00f3 una nueva jornada del torneo de Newcom +60 que se desarroll\u00f3 en el polideportivo Jaime Zapata de Resistencia.<\/p>\n","protected":false},"author":3,"featured_media":375751,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[98],"tags":[],"_links":{"self":[{"href":"https:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/posts\/375750"}],"collection":[{"href":"https:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/comments?post=375750"}],"version-history":[{"count":1,"href":"https:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/posts\/375750\/revisions"}],"predecessor-version":[{"id":375752,"href":"https:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/posts\/375750\/revisions\/375752"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/media\/375751"}],"wp:attachment":[{"href":"https:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/media?parent=375750"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/categories?post=375750"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/tags?post=375750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}