{"id":375762,"date":"2026-07-15T10:38:41","date_gmt":"2026-07-15T13:38:41","guid":{"rendered":"http:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/?p=375762"},"modified":"2026-07-15T10:38:47","modified_gmt":"2026-07-15T13:38:47","slug":"chaco-motociclista-fue-trasladado-de-urgencia-al-chocar-contra-un-auto","status":"publish","type":"post","link":"https:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/2026\/07\/15\/chaco-motociclista-fue-trasladado-de-urgencia-al-chocar-contra-un-auto\/","title":{"rendered":"CHACO: Motociclista Fue Trasladado De Urgencia Al Chocar Contra Un Auto"},"content":{"rendered":"\n<p>El siniestro se produjo sobre la calle 5, en el tramo ubicado entre las calles 2 y 4 de la localidad. Producto del impacto, el conductor del rodado menor sufri\u00f3 un hematoma en el cuero cabelludo y lesiones en una de sus piernas, por lo que fue trasladado de inmediato al nosocomio local. Tras recibir las primeras curaciones y debido a la necesidad de estudios de mayor complejidad, los profesionales m\u00e9dicos dispusieron su derivaci\u00f3n al Hospital 4 de Junio de Presidencia Roque S\u00e1enz Pe\u00f1a. En el lugar del hecho intervino personal policial, que procedi\u00f3 al secuestro de la motocicleta por disposici\u00f3n de la Fiscal\u00eda en turno.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>15-Jul-26  Un motociclista de 59 a\u00f1os result\u00f3 con diversas heridas tras protagonizar un fuerte choque contra un autom\u00f3vil este martes en el casco urbano de General Pinedo. <\/p>\n","protected":false},"author":4,"featured_media":375763,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[103],"tags":[],"_links":{"self":[{"href":"https:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/posts\/375762"}],"collection":[{"href":"https:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/comments?post=375762"}],"version-history":[{"count":1,"href":"https:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/posts\/375762\/revisions"}],"predecessor-version":[{"id":375764,"href":"https:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/posts\/375762\/revisions\/375764"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/media\/375763"}],"wp:attachment":[{"href":"https:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/media?parent=375762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/categories?post=375762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noticiasdelparana.com.ar\/NuevaEdicion\/wp-json\/wp\/v2\/tags?post=375762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}